{"id":62254,"date":"2022-11-16T15:33:13","date_gmt":"2022-11-16T13:33:13","guid":{"rendered":"https:\/\/nitorlack.com\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/"},"modified":"2024-03-28T12:22:04","modified_gmt":"2024-03-28T10:22:04","slug":"problemes-dans-le-processus-de-vernissage-peau-dorange","status":"publish","type":"post","link":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/","title":{"rendered":"Probl\u00e8mes dans le processus de vernissage : Peau d&rsquo;orange"},"content":{"rendered":"<h1><strong>Probl\u00e8mes fr\u00e9quents dans le processus de vernissage : Peau d&rsquo;orange<\/strong><\/h1>\n<p>Au cours du processus de repeinture, diff\u00e9rents probl\u00e8mes et d\u00e9fauts peuvent appara\u00eetre dans la finition de la peinture, obligeant \u00e0 reprendre le processus depuis le d\u00e9but, avec la perte de temps et de mat\u00e9riaux que cela implique. L&rsquo;un des d\u00e9fauts les plus courants dans la peinture des guitares est l&rsquo;effet dit de peau d&rsquo;orange.<\/p>\n<h2><strong>Qu&rsquo;est-ce que l&rsquo;effet peau d&rsquo;orange ?<\/strong><\/h2>\n<p>Le nom de peau d&rsquo;orange vient de la similitude de la finition de la peinture avec la peau d&rsquo;orange. Ce probl\u00e8me est d\u00fb au fait que la peinture n&rsquo;est pas \u00e9tir\u00e9e ou nivel\u00e9e, ce qui entra\u00eene une d\u00e9formation de la surface et augmente l&rsquo;\u00e9paisseur de la couche finale.<\/p>\n<h2><strong>Causes de la peau d&rsquo;orange sur la peinture au pistolet des guitares<\/strong><\/h2>\n<h3 style=\"font-style: normal;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-62232 alignright\" src=\"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-300x225.jpg\" alt=\"defectos del barnizado\" width=\"505\" height=\"379\" srcset=\"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-300x225.jpg 300w, https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-150x112.jpg 150w, https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-267x200.jpg 267w, https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg 587w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/h3>\n<p>La raison de ce d\u00e9faut peut \u00eatre li\u00e9e \u00e0 plusieurs facteurs :<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Le r\u00e9glage de l&rsquo;\u00e9quipement d&rsquo;application est incorrect.<\/strong> L&rsquo;\u00e9quipement de pressurisation, le d\u00e9bit du produit et les mod\u00e8les de ventilateurs doivent \u00eatre correctement r\u00e9gl\u00e9s.<\/li>\n<li><strong>Des pressions d&rsquo;application trop faibles<\/strong> entra\u00eeneront une mauvaise atomisation du produit.<\/li>\n<li><strong>La viscosit\u00e9 de l&rsquo;application est \u00e9lev\u00e9e<\/strong>. Une autre raison pourrait \u00eatre que la viscosit\u00e9 du m\u00e9lange est trop \u00e9lev\u00e9e, ce qui signifie \u00e9galement que la viscosit\u00e9 de l&rsquo;application est trop \u00e9lev\u00e9e. Pour r\u00e9soudre ce probl\u00e8me, nous pouvons r\u00e9duire la viscosit\u00e9 en augmentant l\u00e9g\u00e8rement la dilution du m\u00e9lange. Nous recommandons de commencer avec 10 % de diluant et d&rsquo;ajuster ensuite en fonction du mat\u00e9riel d&rsquo;application.<\/li>\n<li><strong>La couche de base n&rsquo;est pas trop s\u00e8che<\/strong>. Respectez toujours le temps de s\u00e9chage de la couche de base. En r\u00e8gle g\u00e9n\u00e9rale, un s\u00e9chage complet de la nitrocellulose est obtenu entre 12 et 24 heures.<\/li>\n<li><strong>Chargement excessif du produit<\/strong>. Un chargement excessif de produit par passage, et trop \u00e9loign\u00e9 du pistolet par rapport \u00e0 la pi\u00e8ce, entra\u00eene un rev\u00eatement irr\u00e9gulier, ce qui conduit \u00e0 l&rsquo;apparition de d\u00e9fauts de peau d&rsquo;orange.<\/li>\n<li><strong>Mauvaise pr\u00e9paration de l&rsquo;appr\u00eat et mauvais pon\u00e7age<\/strong>. Une pr\u00e9paration et un pon\u00e7age corrects de l&rsquo;appr\u00eat, en respectant toujours le temps de s\u00e9chage de chaque processus, nous aideront \u00e0 obtenir une surface recouverte uniforme et optimis\u00e9e.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2><strong>Causes de la peau d&rsquo;orange sur la peinture au pistolet des guitares<\/strong><\/h2>\n<p>Dans le cas d&rsquo;une<strong> application par pulv\u00e9risation<\/strong>, tous les param\u00e8tres ci-dessus sont d\u00e9j\u00e0 donn\u00e9s par le contenu de la pulv\u00e9risation et le type de buse. Ce qui est essentiel, cependant, c&rsquo;est la distance d&rsquo;application et la vitesse de d\u00e9placement du jet.<\/p>\n<ol>\n<li>Appliquez le spray \u00e0 une <strong>distance moyenne de 25 cm.<\/strong><\/li>\n<li><strong>Secouez<\/strong> bien le spray.<\/li>\n<li>Ne restez pas immobile pendant la pulv\u00e9risation,<strong> continuez toujours \u00e0 vous d\u00e9placer<\/strong> par des mouvements lisses et continus.<\/li>\n<li><strong>L&rsquo;astuce consiste \u00e0 appliquer \u00e0 une vitesse et \u00e0 une distance telles que la peinture couvre suffisamment<\/strong>, sans coulure ni peau d&rsquo;orange.<\/li>\n<\/ol>\n<h2><strong>Comment corriger l&rsquo;effet peau d&rsquo;orange sur la peinture ?<\/strong><\/h2>\n<h3 style=\"font-style: normal;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-62240 alignright\" src=\"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-4fyj-1-300x245.jpg\" alt=\"Piel de naranja \" width=\"474\" height=\"387\" srcset=\"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-4fyj-1-300x245.jpg 300w, https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-4fyj-1-150x123.jpg 150w, https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja-4fyj-1.jpg 550w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/h3>\n<p style=\"font-style: normal;\"><strong>Si le d\u00e9faut de la peau d&rsquo;orange<\/strong> n&rsquo;existe que sur la surface de la pi\u00e8ce, proc\u00e9dez comme suit :<\/p>\n<ol>\n<li style=\"font-style: normal;\">Tout d&rsquo;abord, nous pon\u00e7ons la zone d\u00e9fectueuse avec du <strong>papier de verre<\/strong> <strong>P1500.<\/strong><\/li>\n<li style=\"font-style: normal;\">Nous pon\u00e7ons la surface avec du <strong>papier de verre P2000.<\/strong><\/li>\n<li style=\"font-style: normal;\">Apr\u00e8s avoir ponc\u00e9 la surface,<strong> nous utilisons un chiffon en microfibre pour essuyer la poussi\u00e8re qui en r\u00e9sulte.<\/strong><\/li>\n<li style=\"font-style: normal;\">Ensuite, nous utiliserons <strong>une polisseuse<\/strong> pour un polissage \u00e0 coupe rapide, en appliquant une pression et un mouvement uniforme. Enfin, nous nettoierons la zone avec du ballet pour \u00e9valuer les r\u00e9sultats obtenus.<\/li>\n<\/ol>\n<p>En revanche, s&rsquo;il reste des d\u00e9fauts de peau d&rsquo;orange dans la finition, et que l&rsquo;\u00e9paisseur est trop importante, le polissage ne sera pas suffisant.<\/p>\n<p>Dans ce cas hypoth\u00e9tique, <strong>nous devons pr\u00e9parer la surface pour commencer le processus de peinture \u00e0 partir de z\u00e9ro:<\/strong><\/p>\n<p>Pour \u00e9viter que ce d\u00e9faut n&rsquo;apparaisse sur la surface de votre guitare, il est essentiel de suivre ces conseils d&rsquo;application, ainsi que l&rsquo;utilisation de produits <strong>NITORLACK<\/strong> sp\u00e9cifiques.<\/p>\n<p>Ces vernis et peintures ont \u00e9t\u00e9 formul\u00e9s avec une <strong>\u00e9vaporation \u00e9quilibr\u00e9e des solvants pour minimiser ce d\u00e9faut d&rsquo;application.<\/strong> L&rsquo;application de ce <a href=\"https:\/\/nitorlack.com\/fr\/barniz\/dissolvants\/dissolvants-fr\/solvent-medium-copiar\/\">solvant<\/a> permet \u00e9galement de r\u00e9duire le risque que cela se produise.<\/p>\n<p>Vous pouvez regarder les tutoriels sur notre site web et sur <a href=\"https:\/\/www.youtube.com\/channel\/UCF0Oyo44SRnpoCRPVeya3SQ\/featured\">Youtube<\/a>. Si vous avez encore des doutes, vous pouvez nous les demander dans notre support personnalis\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Probl\u00e8mes fr\u00e9quents dans le processus de vernissage : Peau d&rsquo;orange Au cours du [&hellip;]<\/p>\n","protected":false},"author":33274,"featured_media":62234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7503],"tags":[],"class_list":["post-62254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9fauts du vernis : Peau d&#039;orange : NITORLACK<\/title>\n<meta name=\"description\" content=\"Pourquoi ce probl\u00e8me se produit-il dans le processus de peinture ou de vernissage et comment le pr\u00e9venir et le r\u00e9soudre ? - Nitorlack\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9fauts du vernis : Peau d&#039;orange : NITORLACK\" \/>\n<meta property=\"og:description\" content=\"Pourquoi ce probl\u00e8me se produit-il dans le processus de peinture ou de vernissage et comment le pr\u00e9venir et le r\u00e9soudre ? - Nitorlack\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/\" \/>\n<meta property=\"og:site_name\" content=\"Nitorlack\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-16T13:33:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T10:22:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"587\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jose Pardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Pardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/\"},\"author\":{\"name\":\"Jose Pardo\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#\\\/schema\\\/person\\\/51b7c1a21e881e505bf8d48acd6fe152\"},\"headline\":\"Probl\u00e8mes dans le processus de vernissage : Peau d&rsquo;orange\",\"datePublished\":\"2022-11-16T13:33:13+00:00\",\"dateModified\":\"2024-03-28T10:22:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/\"},\"wordCount\":794,\"publisher\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nitorlack.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/piel-de-naranja.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/\",\"url\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/\",\"name\":\"D\u00e9fauts du vernis : Peau d'orange : NITORLACK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nitorlack.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/piel-de-naranja.jpg\",\"datePublished\":\"2022-11-16T13:33:13+00:00\",\"dateModified\":\"2024-03-28T10:22:04+00:00\",\"description\":\"Pourquoi ce probl\u00e8me se produit-il dans le processus de peinture ou de vernissage et comment le pr\u00e9venir et le r\u00e9soudre ? - Nitorlack\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nitorlack.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/piel-de-naranja.jpg\",\"contentUrl\":\"https:\\\/\\\/nitorlack.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/piel-de-naranja.jpg\",\"width\":587,\"height\":440,\"caption\":\"defectos del barnizado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/blog\\\/problemes-dans-le-processus-de-vernissage-peau-dorange\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page de Couverture\",\"item\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Probl\u00e8mes dans le processus de vernissage : Peau d&#8217;orange\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/\",\"name\":\"Nitorlack\",\"description\":\"Guitar Lacquers\",\"publisher\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#organization\",\"name\":\"Nitorlack\",\"url\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cropped-galleta-negra-1.jpg\",\"contentUrl\":\"http:\\\/\\\/nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cropped-galleta-negra-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Nitorlack\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nitorlack.com\\\/fr\\\/#\\\/schema\\\/person\\\/51b7c1a21e881e505bf8d48acd6fe152\",\"name\":\"Jose Pardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d1c267b2b359b673da9c039de5c94642b66b0e654811a8db3ad3d5b1104d4cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d1c267b2b359b673da9c039de5c94642b66b0e654811a8db3ad3d5b1104d4cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d1c267b2b359b673da9c039de5c94642b66b0e654811a8db3ad3d5b1104d4cc?s=96&d=mm&r=g\",\"caption\":\"Jose Pardo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9fauts du vernis : Peau d'orange : NITORLACK","description":"Pourquoi ce probl\u00e8me se produit-il dans le processus de peinture ou de vernissage et comment le pr\u00e9venir et le r\u00e9soudre ? - Nitorlack","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9fauts du vernis : Peau d'orange : NITORLACK","og_description":"Pourquoi ce probl\u00e8me se produit-il dans le processus de peinture ou de vernissage et comment le pr\u00e9venir et le r\u00e9soudre ? - Nitorlack","og_url":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/","og_site_name":"Nitorlack","article_published_time":"2022-11-16T13:33:13+00:00","article_modified_time":"2024-03-28T10:22:04+00:00","og_image":[{"width":587,"height":440,"url":"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg","type":"image\/jpeg"}],"author":"Jose Pardo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jose Pardo","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#article","isPartOf":{"@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/"},"author":{"name":"Jose Pardo","@id":"https:\/\/nitorlack.com\/fr\/#\/schema\/person\/51b7c1a21e881e505bf8d48acd6fe152"},"headline":"Probl\u00e8mes dans le processus de vernissage : Peau d&rsquo;orange","datePublished":"2022-11-16T13:33:13+00:00","dateModified":"2024-03-28T10:22:04+00:00","mainEntityOfPage":{"@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/"},"wordCount":794,"publisher":{"@id":"https:\/\/nitorlack.com\/fr\/#organization"},"image":{"@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#primaryimage"},"thumbnailUrl":"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/","url":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/","name":"D\u00e9fauts du vernis : Peau d'orange : NITORLACK","isPartOf":{"@id":"https:\/\/nitorlack.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#primaryimage"},"image":{"@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#primaryimage"},"thumbnailUrl":"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg","datePublished":"2022-11-16T13:33:13+00:00","dateModified":"2024-03-28T10:22:04+00:00","description":"Pourquoi ce probl\u00e8me se produit-il dans le processus de peinture ou de vernissage et comment le pr\u00e9venir et le r\u00e9soudre ? - Nitorlack","breadcrumb":{"@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#primaryimage","url":"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg","contentUrl":"https:\/\/nitorlack.com\/wp-content\/uploads\/2022\/11\/piel-de-naranja.jpg","width":587,"height":440,"caption":"defectos del barnizado"},{"@type":"BreadcrumbList","@id":"https:\/\/nitorlack.com\/fr\/blog\/problemes-dans-le-processus-de-vernissage-peau-dorange\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page de Couverture","item":"https:\/\/nitorlack.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Probl\u00e8mes dans le processus de vernissage : Peau d&#8217;orange"}]},{"@type":"WebSite","@id":"https:\/\/nitorlack.com\/fr\/#website","url":"https:\/\/nitorlack.com\/fr\/","name":"Nitorlack","description":"Guitar Lacquers","publisher":{"@id":"https:\/\/nitorlack.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitorlack.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nitorlack.com\/fr\/#organization","name":"Nitorlack","url":"https:\/\/nitorlack.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nitorlack.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/nitorlack.com\/wp-content\/uploads\/2016\/02\/cropped-galleta-negra-1.jpg","contentUrl":"http:\/\/nitorlack.com\/wp-content\/uploads\/2016\/02\/cropped-galleta-negra-1.jpg","width":512,"height":512,"caption":"Nitorlack"},"image":{"@id":"https:\/\/nitorlack.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nitorlack.com\/fr\/#\/schema\/person\/51b7c1a21e881e505bf8d48acd6fe152","name":"Jose Pardo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d1c267b2b359b673da9c039de5c94642b66b0e654811a8db3ad3d5b1104d4cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d1c267b2b359b673da9c039de5c94642b66b0e654811a8db3ad3d5b1104d4cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d1c267b2b359b673da9c039de5c94642b66b0e654811a8db3ad3d5b1104d4cc?s=96&d=mm&r=g","caption":"Jose Pardo"}}]}},"_links":{"self":[{"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/posts\/62254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/users\/33274"}],"replies":[{"embeddable":true,"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/comments?post=62254"}],"version-history":[{"count":0,"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/posts\/62254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/media\/62234"}],"wp:attachment":[{"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/media?parent=62254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/categories?post=62254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nitorlack.com\/fr\/wp-json\/wp\/v2\/tags?post=62254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}